{"id":22233,"date":"2022-08-08T07:46:30","date_gmt":"2022-08-08T07:46:30","guid":{"rendered":"https:\/\/www.smartray.com\/?p=22233"},"modified":"2025-12-10T16:25:12","modified_gmt":"2025-12-10T16:25:12","slug":"smartray-praesentiert-absolute-neuheit-in-der-3d-schweissnahtinspektion-maximale-erreichbarkeit-durch-innovatives-sensordesign","status":"publish","type":"post","link":"https:\/\/www.smartray.com\/de\/news\/smartray-praesentiert-absolute-neuheit-in-der-3d-schweissnahtinspektion-maximale-erreichbarkeit-durch-innovatives-sensordesign\/","title":{"rendered":"SmartRay pr\u00e4sentiert absolute Neuheit in der 3D-Schwei\u00dfnahtinspektion \u2013 Maximale Erreichbarkeit durch innovatives Sensordesign"},"content":{"rendered":"<p><img decoding=\"async\" class=\"size-medium wp-image-22213 alignleft\" src=\"https:\/\/www.smartray.com\/wp-content\/uploads\/2022\/06\/211222_SR_MICO_SingleVisual_Mico_compressed-300x212.jpg\" alt=\"\" width=\"300\" height=\"212\" srcset=\"https:\/\/www.smartray.com\/wp-content\/uploads\/2022\/06\/211222_SR_MICO_SingleVisual_Mico_compressed-200x141.jpg 200w, https:\/\/www.smartray.com\/wp-content\/uploads\/2022\/06\/211222_SR_MICO_SingleVisual_Mico_compressed-300x212.jpg 300w, https:\/\/www.smartray.com\/wp-content\/uploads\/2022\/06\/211222_SR_MICO_SingleVisual_Mico_compressed-400x283.jpg 400w, https:\/\/www.smartray.com\/wp-content\/uploads\/2022\/06\/211222_SR_MICO_SingleVisual_Mico_compressed-600x424.jpg 600w, https:\/\/www.smartray.com\/wp-content\/uploads\/2022\/06\/211222_SR_MICO_SingleVisual_Mico_compressed-768x543.jpg 768w, https:\/\/www.smartray.com\/wp-content\/uploads\/2022\/06\/211222_SR_MICO_SingleVisual_Mico_compressed-800x565.jpg 800w, https:\/\/www.smartray.com\/wp-content\/uploads\/2022\/06\/211222_SR_MICO_SingleVisual_Mico_compressed-1024x724.jpg 1024w, https:\/\/www.smartray.com\/wp-content\/uploads\/2022\/06\/211222_SR_MICO_SingleVisual_Mico_compressed-1200x848.jpg 1200w, https:\/\/www.smartray.com\/wp-content\/uploads\/2022\/06\/211222_SR_MICO_SingleVisual_Mico_compressed-1536x1086.jpg 1536w, https:\/\/www.smartray.com\/wp-content\/uploads\/2022\/06\/211222_SR_MICO_SingleVisual_Mico_compressed.jpg 1722w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>SmartRay stellt einen neuen 3D Sensor speziell f\u00fcr die Schwei\u00dfnahtpr\u00fcfung vor. Als technologische Premiere verf\u00fcgt der MICO-Sensor \u00fcber den gleichen Formfaktor eines Schwei\u00dfbrenners und ist damit alleinstehend in dieser anspruchsvollen Anwendung.<\/p>\n<p>Mit dem neuartigen Sensordesign schafft es SmartRay einen Standard Schwei\u00dfbrenner nachzuahmen. Durch den identischen Werkzeugmittelpunkt (tool center point; TCP) sowie der gleichen Kontur beider Systeme, ist es m\u00f6glich alles zu inspizieren, was geschwei\u00dft ist; eine wichtige Entwicklung in diesem Prozess. Mit der d\u00fcnnen und kompakten Form erm\u00f6glicht der Sensor die Inspektion wo vormals keine automatisierte Inspektion m\u00f6glich war und somit eine vollst\u00e4ndige Integration der Schwei\u00dfnahtpr\u00fcfung in die meisten Produktionslinien.<\/p>\n<p>Der winzige Sensorkopf hat eine Aufl\u00f6sung von etwas \u00fcber 1000 Pixel auf einem Sichtfeld von 40 mm \u2013 die perfekte Optimierung f\u00fcr automatisierte Schwei\u00dfnahtpr\u00fcfsysteme. Folglich betr\u00e4gt die laterale Aufl\u00f6sung dieses Sensors 40 \u00b5m. Um dies in einen Zusammenhang zu bringen: Ein menschliches Haar hat einen Durchmesser von etwa 70 \u00b5m. Das hei\u00dft, der Abstand zwischen den empfangenen Messdaten ist weit kleiner als der Durchmesser eines menschlichen Haares. Dies erm\u00f6glicht die Erkennung sehr feiner Defekte an einer Schwei\u00dfnaht. Kunden ben\u00f6tigen typischerweise einen Sensor, um Defekte mit einer Gr\u00f6\u00dfe von etwa 0,5 Millimetern und manchmal 0,3 oder 0,2 Millimetern zu identifizieren. Dieser Sensor kann Fehler ab 0,2 Millimeter Durchmesser zuverl\u00e4ssig erkennen.<\/p>\n<p>Neben dem neuen Design ist der neue Sensor auch deutlich schneller als die Vorg\u00e4ngermodelle. MICO arbeitet mit etwa 3 kHz und f\u00fchrt 3000 Profilschnitte pro Sekunde aus \u2013 50 % schneller als die vorherige Standardanwendung. Die normale Inspektionsgeschwindigkeit dieses Sensors betr\u00e4gt 200 Millimeter\/Sekunde im Vergleich zu anderen Systemen, die mit einer Standardgeschwindigkeit von 100-130 Millimetern pro Sekunde pr\u00fcfen. Infolgedessen k\u00f6nnen Kunden mit einer gro\u00dfen Anzahl von Schwei\u00dfn\u00e4hten, die innerhalb einer kurzen Zykluszeit zu pr\u00fcfen sind, die Pr\u00fcfzeit verk\u00fcrzen und ben\u00f6tigen m\u00f6glicherweise weniger Systeme, um dieselben Schwei\u00dfn\u00e4hte zu pr\u00fcfen.<\/p>\n<p>Mit diesem neuen Design hat SmartRay auch eine interne Verkabelung f\u00fcr Hohlarmroboter erm\u00f6glicht, wodurch die Notwendigkeit externer Roboterschlauchpakete entf\u00e4llt. Dies ist nicht nur kosteng\u00fcnstiger, sondern vor allem hinsichtlich der Erreichbarkeit vorteilhafter, da die St\u00f6rkonturen eines Schlauchpakets vermieden werden. Die Wartungszeit wird au\u00dferdem erheblich reduziert, da der Verschlei\u00df dieser Kabel abnimmt und ein Adapterkabel, das normalerweise im \u00dcbergang vom Sensor zum Roboterkabelpaket ben\u00f6tigt wurde, \u00fcberfl\u00fcssig wird, somit ist ein Kabel weniger vorhanden ist.<\/p>\n<p>Au\u00dferdem musste ein Integrator in der Vergangenheit einen eigenen projektspezifischen Roboterflansch konstruieren und fertigen, um den Sensor aufzunehmen und eine m\u00f6glichst gute Erreichbarkeit zu erzielen. Der MICO-Sensor macht dies \u00fcberfl\u00fcssig, da er in einem vollst\u00e4ndig integrierten Design direkt am Roboterflansch montiert werden kann. Der Vorteil ist erheblich, da Anwender kein individuelles Design von einem Anlagenbauer oder Integrator ben\u00f6tigen. Durch die Eliminierung eines zus\u00e4tzlichen Elements reduzieren sich Kosten und das Implementierungsrisiko deutlich.<\/p>\n<p>\u201eDie Resonanz auf dem Markt war \u00fcberw\u00e4ltigend. Da der Sensor und der Schwei\u00dfbrenner den gleichen Formfaktor haben, profitieren Kunden von einer viel besseren Erreichbarkeit und ben\u00f6tigen nur einen Simulationsprozess. Dies spart viel Zeit beim Prozessdesign, macht die Gesamtproduktion effizienter und erh\u00f6ht die Kapitalrendite\u201c sagt Bernd Lor\u00f6sch, Business Unit Manager, JOSY Schwei\u00dfnahtpr\u00fcfung, SmartRay.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SmartRay stellt einen neuen 3D Sensor speziell f\u00fcr die Schwei\u00dfnahtpr\u00fcfung vor. Als technologische Premiere verf\u00fcgt der MICO-Sensor \u00fcber den gleichen Formfaktor eines Schwei\u00dfbrenners und ist damit alleinstehend in dieser anspruchsvollen Anwendung. Mit dem neuartigen Sensordesign schafft es SmartRay einen Standard Schwei\u00dfbrenner nachzuahmen. Durch den identischen Werkzeugmittelpunkt (tool center point; TCP) sowie der gleichen Kontur beider <a href=\"https:\/\/www.smartray.com\/de\/news\/smartray-praesentiert-absolute-neuheit-in-der-3d-schweissnahtinspektion-maximale-erreichbarkeit-durch-innovatives-sensordesign\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":12,"featured_media":22230,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"aside","meta":{"footnotes":""},"categories":[43],"tags":[],"class_list":["post-22233","post","type-post","status-publish","format-aside","has-post-thumbnail","hentry","category-smartray","post_format-post-format-aside"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SmartRay pr\u00e4sentiert absolute Neuheit in der 3D-Schwei\u00dfnahtinspektion \u2013 Maximale Erreichbarkeit durch innovatives Sensordesign - SmartRay<\/title>\n<meta name=\"description\" content=\"MICO: 3D-Schwei\u00dfnahtinspektion mit maximaler Erreichbarkeit durch innovatives Design in Brenner-Form. 50 % schneller und 40 \u00b5m Aufl\u00f6sung!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.smartray.com\/de\/news\/smartray-praesentiert-absolute-neuheit-in-der-3d-schweissnahtinspektion-maximale-erreichbarkeit-durch-innovatives-sensordesign\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SmartRay pr\u00e4sentiert absolute Neuheit in der 3D-Schwei\u00dfnahtinspektion \u2013 Maximale Erreichbarkeit durch innovatives Sensordesign - SmartRay\" \/>\n<meta property=\"og:description\" content=\"MICO: 3D-Schwei\u00dfnahtinspektion mit maximaler Erreichbarkeit durch innovatives Design in Brenner-Form. 50 % schneller und 40 \u00b5m Aufl\u00f6sung!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.smartray.com\/de\/news\/smartray-praesentiert-absolute-neuheit-in-der-3d-schweissnahtinspektion-maximale-erreichbarkeit-durch-innovatives-sensordesign\/\" \/>\n<meta property=\"og:site_name\" content=\"SmartRay\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-08T07:46:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-10T16:25:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.smartray.com\/wp-content\/uploads\/2022\/08\/MICO_News.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"320\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Isabel Maier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Isabel Maier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.smartray.com\\\/de\\\/news\\\/smartray-praesentiert-absolute-neuheit-in-der-3d-schweissnahtinspektion-maximale-erreichbarkeit-durch-innovatives-sensordesign\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.smartray.com\\\/de\\\/news\\\/smartray-praesentiert-absolute-neuheit-in-der-3d-schweissnahtinspektion-maximale-erreichbarkeit-durch-innovatives-sensordesign\\\/\"},\"author\":{\"name\":\"Isabel Maier\",\"@id\":\"https:\\\/\\\/www.smartray.com\\\/de\\\/#\\\/schema\\\/person\\\/37e79552f4670642e66586a2e23a295d\"},\"headline\":\"SmartRay pr\u00e4sentiert absolute Neuheit in der 3D-Schwei\u00dfnahtinspektion \u2013 Maximale Erreichbarkeit durch innovatives Sensordesign\",\"datePublished\":\"2022-08-08T07:46:30+00:00\",\"dateModified\":\"2025-12-10T16:25:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.smartray.com\\\/de\\\/news\\\/smartray-praesentiert-absolute-neuheit-in-der-3d-schweissnahtinspektion-maximale-erreichbarkeit-durch-innovatives-sensordesign\\\/\"},\"wordCount\":555,\"image\":{\"@id\":\"https:\\\/\\\/www.smartray.com\\\/de\\\/news\\\/smartray-praesentiert-absolute-neuheit-in-der-3d-schweissnahtinspektion-maximale-erreichbarkeit-durch-innovatives-sensordesign\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.smartray.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/MICO_News.jpg\",\"articleSection\":[\"SmartRay\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.smartray.com\\\/de\\\/news\\\/smartray-praesentiert-absolute-neuheit-in-der-3d-schweissnahtinspektion-maximale-erreichbarkeit-durch-innovatives-sensordesign\\\/\",\"url\":\"https:\\\/\\\/www.smartray.com\\\/de\\\/news\\\/smartray-praesentiert-absolute-neuheit-in-der-3d-schweissnahtinspektion-maximale-erreichbarkeit-durch-innovatives-sensordesign\\\/\",\"name\":\"SmartRay pr\u00e4sentiert absolute Neuheit in der 3D-Schwei\u00dfnahtinspektion \u2013 Maximale Erreichbarkeit durch innovatives Sensordesign - SmartRay\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.smartray.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.smartray.com\\\/de\\\/news\\\/smartray-praesentiert-absolute-neuheit-in-der-3d-schweissnahtinspektion-maximale-erreichbarkeit-durch-innovatives-sensordesign\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.smartray.com\\\/de\\\/news\\\/smartray-praesentiert-absolute-neuheit-in-der-3d-schweissnahtinspektion-maximale-erreichbarkeit-durch-innovatives-sensordesign\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.smartray.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/MICO_News.jpg\",\"datePublished\":\"2022-08-08T07:46:30+00:00\",\"dateModified\":\"2025-12-10T16:25:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.smartray.com\\\/de\\\/#\\\/schema\\\/person\\\/37e79552f4670642e66586a2e23a295d\"},\"description\":\"MICO: 3D-Schwei\u00dfnahtinspektion mit maximaler Erreichbarkeit durch innovatives Design in Brenner-Form. 50 % schneller und 40 \u00b5m Aufl\u00f6sung!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.smartray.com\\\/de\\\/news\\\/smartray-praesentiert-absolute-neuheit-in-der-3d-schweissnahtinspektion-maximale-erreichbarkeit-durch-innovatives-sensordesign\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.smartray.com\\\/de\\\/news\\\/smartray-praesentiert-absolute-neuheit-in-der-3d-schweissnahtinspektion-maximale-erreichbarkeit-durch-innovatives-sensordesign\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.smartray.com\\\/de\\\/news\\\/smartray-praesentiert-absolute-neuheit-in-der-3d-schweissnahtinspektion-maximale-erreichbarkeit-durch-innovatives-sensordesign\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.smartray.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/MICO_News.jpg\",\"contentUrl\":\"https:\\\/\\\/www.smartray.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/MICO_News.jpg\",\"width\":320,\"height\":200,\"caption\":\"no constraints in weld inspection\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.smartray.com\\\/de\\\/news\\\/smartray-praesentiert-absolute-neuheit-in-der-3d-schweissnahtinspektion-maximale-erreichbarkeit-durch-innovatives-sensordesign\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.smartray.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SmartRay pr\u00e4sentiert absolute Neuheit in der 3D-Schwei\u00dfnahtinspektion \u2013 Maximale Erreichbarkeit durch innovatives Sensordesign\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.smartray.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.smartray.com\\\/de\\\/\",\"name\":\"SmartRay\",\"description\":\"Cutting-edge 3D sensors for inspection, guidance and measurement\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.smartray.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.smartray.com\\\/de\\\/#\\\/schema\\\/person\\\/37e79552f4670642e66586a2e23a295d\",\"name\":\"Isabel Maier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6a06ae7a4142503ef7853645b4d8d4fa82ca2394154dcd8ddd9b530da48b749f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6a06ae7a4142503ef7853645b4d8d4fa82ca2394154dcd8ddd9b530da48b749f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6a06ae7a4142503ef7853645b4d8d4fa82ca2394154dcd8ddd9b530da48b749f?s=96&d=mm&r=g\",\"caption\":\"Isabel Maier\"},\"url\":\"https:\\\/\\\/www.smartray.com\\\/de\\\/news\\\/author\\\/isabel-maiersmartray-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SmartRay pr\u00e4sentiert absolute Neuheit in der 3D-Schwei\u00dfnahtinspektion \u2013 Maximale Erreichbarkeit durch innovatives Sensordesign - SmartRay","description":"MICO: 3D-Schwei\u00dfnahtinspektion mit maximaler Erreichbarkeit durch innovatives Design in Brenner-Form. 50 % schneller und 40 \u00b5m Aufl\u00f6sung!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.smartray.com\/de\/news\/smartray-praesentiert-absolute-neuheit-in-der-3d-schweissnahtinspektion-maximale-erreichbarkeit-durch-innovatives-sensordesign\/","og_locale":"de_DE","og_type":"article","og_title":"SmartRay pr\u00e4sentiert absolute Neuheit in der 3D-Schwei\u00dfnahtinspektion \u2013 Maximale Erreichbarkeit durch innovatives Sensordesign - SmartRay","og_description":"MICO: 3D-Schwei\u00dfnahtinspektion mit maximaler Erreichbarkeit durch innovatives Design in Brenner-Form. 50 % schneller und 40 \u00b5m Aufl\u00f6sung!","og_url":"https:\/\/www.smartray.com\/de\/news\/smartray-praesentiert-absolute-neuheit-in-der-3d-schweissnahtinspektion-maximale-erreichbarkeit-durch-innovatives-sensordesign\/","og_site_name":"SmartRay","article_published_time":"2022-08-08T07:46:30+00:00","article_modified_time":"2025-12-10T16:25:12+00:00","og_image":[{"width":320,"height":200,"url":"https:\/\/www.smartray.com\/wp-content\/uploads\/2022\/08\/MICO_News.jpg","type":"image\/jpeg"}],"author":"Isabel Maier","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Isabel Maier","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.smartray.com\/de\/news\/smartray-praesentiert-absolute-neuheit-in-der-3d-schweissnahtinspektion-maximale-erreichbarkeit-durch-innovatives-sensordesign\/#article","isPartOf":{"@id":"https:\/\/www.smartray.com\/de\/news\/smartray-praesentiert-absolute-neuheit-in-der-3d-schweissnahtinspektion-maximale-erreichbarkeit-durch-innovatives-sensordesign\/"},"author":{"name":"Isabel Maier","@id":"https:\/\/www.smartray.com\/de\/#\/schema\/person\/37e79552f4670642e66586a2e23a295d"},"headline":"SmartRay pr\u00e4sentiert absolute Neuheit in der 3D-Schwei\u00dfnahtinspektion \u2013 Maximale Erreichbarkeit durch innovatives Sensordesign","datePublished":"2022-08-08T07:46:30+00:00","dateModified":"2025-12-10T16:25:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.smartray.com\/de\/news\/smartray-praesentiert-absolute-neuheit-in-der-3d-schweissnahtinspektion-maximale-erreichbarkeit-durch-innovatives-sensordesign\/"},"wordCount":555,"image":{"@id":"https:\/\/www.smartray.com\/de\/news\/smartray-praesentiert-absolute-neuheit-in-der-3d-schweissnahtinspektion-maximale-erreichbarkeit-durch-innovatives-sensordesign\/#primaryimage"},"thumbnailUrl":"https:\/\/www.smartray.com\/wp-content\/uploads\/2022\/08\/MICO_News.jpg","articleSection":["SmartRay"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.smartray.com\/de\/news\/smartray-praesentiert-absolute-neuheit-in-der-3d-schweissnahtinspektion-maximale-erreichbarkeit-durch-innovatives-sensordesign\/","url":"https:\/\/www.smartray.com\/de\/news\/smartray-praesentiert-absolute-neuheit-in-der-3d-schweissnahtinspektion-maximale-erreichbarkeit-durch-innovatives-sensordesign\/","name":"SmartRay pr\u00e4sentiert absolute Neuheit in der 3D-Schwei\u00dfnahtinspektion \u2013 Maximale Erreichbarkeit durch innovatives Sensordesign - SmartRay","isPartOf":{"@id":"https:\/\/www.smartray.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.smartray.com\/de\/news\/smartray-praesentiert-absolute-neuheit-in-der-3d-schweissnahtinspektion-maximale-erreichbarkeit-durch-innovatives-sensordesign\/#primaryimage"},"image":{"@id":"https:\/\/www.smartray.com\/de\/news\/smartray-praesentiert-absolute-neuheit-in-der-3d-schweissnahtinspektion-maximale-erreichbarkeit-durch-innovatives-sensordesign\/#primaryimage"},"thumbnailUrl":"https:\/\/www.smartray.com\/wp-content\/uploads\/2022\/08\/MICO_News.jpg","datePublished":"2022-08-08T07:46:30+00:00","dateModified":"2025-12-10T16:25:12+00:00","author":{"@id":"https:\/\/www.smartray.com\/de\/#\/schema\/person\/37e79552f4670642e66586a2e23a295d"},"description":"MICO: 3D-Schwei\u00dfnahtinspektion mit maximaler Erreichbarkeit durch innovatives Design in Brenner-Form. 50 % schneller und 40 \u00b5m Aufl\u00f6sung!","breadcrumb":{"@id":"https:\/\/www.smartray.com\/de\/news\/smartray-praesentiert-absolute-neuheit-in-der-3d-schweissnahtinspektion-maximale-erreichbarkeit-durch-innovatives-sensordesign\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.smartray.com\/de\/news\/smartray-praesentiert-absolute-neuheit-in-der-3d-schweissnahtinspektion-maximale-erreichbarkeit-durch-innovatives-sensordesign\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.smartray.com\/de\/news\/smartray-praesentiert-absolute-neuheit-in-der-3d-schweissnahtinspektion-maximale-erreichbarkeit-durch-innovatives-sensordesign\/#primaryimage","url":"https:\/\/www.smartray.com\/wp-content\/uploads\/2022\/08\/MICO_News.jpg","contentUrl":"https:\/\/www.smartray.com\/wp-content\/uploads\/2022\/08\/MICO_News.jpg","width":320,"height":200,"caption":"no constraints in weld inspection"},{"@type":"BreadcrumbList","@id":"https:\/\/www.smartray.com\/de\/news\/smartray-praesentiert-absolute-neuheit-in-der-3d-schweissnahtinspektion-maximale-erreichbarkeit-durch-innovatives-sensordesign\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.smartray.com\/de\/"},{"@type":"ListItem","position":2,"name":"SmartRay pr\u00e4sentiert absolute Neuheit in der 3D-Schwei\u00dfnahtinspektion \u2013 Maximale Erreichbarkeit durch innovatives Sensordesign"}]},{"@type":"WebSite","@id":"https:\/\/www.smartray.com\/de\/#website","url":"https:\/\/www.smartray.com\/de\/","name":"SmartRay","description":"Cutting-edge 3D sensors for inspection, guidance and measurement","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.smartray.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.smartray.com\/de\/#\/schema\/person\/37e79552f4670642e66586a2e23a295d","name":"Isabel Maier","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/6a06ae7a4142503ef7853645b4d8d4fa82ca2394154dcd8ddd9b530da48b749f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6a06ae7a4142503ef7853645b4d8d4fa82ca2394154dcd8ddd9b530da48b749f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6a06ae7a4142503ef7853645b4d8d4fa82ca2394154dcd8ddd9b530da48b749f?s=96&d=mm&r=g","caption":"Isabel Maier"},"url":"https:\/\/www.smartray.com\/de\/news\/author\/isabel-maiersmartray-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.smartray.com\/de\/wp-json\/wp\/v2\/posts\/22233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.smartray.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.smartray.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.smartray.com\/de\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.smartray.com\/de\/wp-json\/wp\/v2\/comments?post=22233"}],"version-history":[{"count":1,"href":"https:\/\/www.smartray.com\/de\/wp-json\/wp\/v2\/posts\/22233\/revisions"}],"predecessor-version":[{"id":22234,"href":"https:\/\/www.smartray.com\/de\/wp-json\/wp\/v2\/posts\/22233\/revisions\/22234"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.smartray.com\/de\/wp-json\/wp\/v2\/media\/22230"}],"wp:attachment":[{"href":"https:\/\/www.smartray.com\/de\/wp-json\/wp\/v2\/media?parent=22233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.smartray.com\/de\/wp-json\/wp\/v2\/categories?post=22233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.smartray.com\/de\/wp-json\/wp\/v2\/tags?post=22233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}